{"id":3411,"date":"2021-09-10T12:04:32","date_gmt":"2021-09-10T12:04:32","guid":{"rendered":"http:\/\/dummy.xtemos.com\/woodmart2\/elementor\/?page_id=3411"},"modified":"2026-02-02T11:53:47","modified_gmt":"2026-02-02T11:53:47","slug":"home-shoes","status":"publish","type":"page","link":"https:\/\/savo.ae\/ar\/","title":{"rendered":"Home Shoes"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"3411\" class=\"elementor elementor-3411\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-fa37859 e-flex e-con-boxed e-con e-parent\" data-id=\"fa37859\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6af413c elementor-widget elementor-widget-wd_slider\" data-id=\"6af413c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_slider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<link rel=\"stylesheet\" id=\"xts-style-term-70-css\" href=\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/xts-term-70-1752466548.css?ver=8.0.6\" type=\"text\/css\" media=\"all\">  \t\t\t<style>\t\t\t\t\t\t\t#slide-27438 .wd-slide-container {\n\t\t\t\t\t\t\t\t\t\t--wd-align-items: center;\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t--wd-justify-content: left;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t#slide-27438.woodmart-loaded .wd-slide-bg {\n\t\t\t\t\t\t\t\t}\n\n\t\t\t\t#slide-27438 .wd-slide-bg {\n\t\t\t\tbackground-color:rgb(245,240,234);\t\t\t\tbackground-size:cover;\n\t\t\t\t\t\t\t\t\t\tbackground-position:center center;\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\n\t\t\t\t@media (max-width: 1024px) {\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t#slide-27438 .wd-slide-bg {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t}\n\n\t\t\t\t@media (max-width: 768px) {\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t#slide-27438 .wd-slide-bg {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t}\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t#slide-27457 .wd-slide-container {\n\t\t\t\t\t\t\t\t\t\t--wd-align-items: center;\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t--wd-justify-content: left;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t#slide-27457.woodmart-loaded .wd-slide-bg {\n\t\t\t\t\t\t\t\t}\n\n\t\t\t\t#slide-27457 .wd-slide-bg {\n\t\t\t\tbackground-color:rgb(245,240,234);\t\t\t\tbackground-size:cover;\n\t\t\t\t\t\t\t\t\t\tbackground-position:center center;\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\n\t\t\t\t@media (max-width: 1024px) {\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t#slide-27457 .wd-slide-bg {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t}\n\n\t\t\t\t@media (max-width: 768px) {\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t#slide-27457 .wd-slide-bg {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t}\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t#slide-27463 .wd-slide-container {\n\t\t\t\t\t\t\t\t\t\t--wd-align-items: center;\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t--wd-justify-content: left;\n\t\t\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\t\t#slide-27463.woodmart-loaded .wd-slide-bg {\n\t\t\t\t\t\t\t\t}\n\n\t\t\t\t#slide-27463 .wd-slide-bg {\n\t\t\t\tbackground-color:rgb(245,240,234);\t\t\t\tbackground-size:cover;\n\t\t\t\t\t\t\t\t\t\tbackground-position:center center;\t\t\t\t\t\t\t\t\t}\n\n\t\t\t\t\n\t\t\t\t@media (max-width: 1024px) {\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t#slide-27463 .wd-slide-bg {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t}\n\n\t\t\t\t@media (max-width: 768px) {\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t#slide-27463 .wd-slide-bg {\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t}\n\t\t\t\t}\n\n\t\t\t\t\n\t\t\t\t\t\t\t\t<\/style>\n\t\t<div id=\"slider-70\" data-id=\"70\" class=\"wd-slider wd-carousel-container wd-anim-slide wd-section-stretch\">\n\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t<div class=\"wd-carousel wd-grid\" data-speed=\"25000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-autoheight=\"yes\" data-scroll_per_page=\"yes\" data-sliding_speed=\"700\" data-effect=\"slide\" style=\"--wd-col-lg:1;--wd-col-md:1;--wd-col-sm:1;\">\n\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"slide-27438\" class=\"wd-slide wd-carousel-item woodmart-loaded\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container wd-slide-container content-full-width wd-padding-off\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-slide-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>.elementor-27438 .elementor-element.elementor-element-0090827{--display:flex;--min-height:600px;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--justify-content:center;--align-items:flex-end;--gap:30px 20px;--row-gap:30px;--column-gap:20px;--overlay-opacity:0.1;--padding-top:0px;--padding-bottom:50px;--padding-left:70px;--padding-right:70px;}.elementor-27438 .elementor-element.elementor-element-0090827:not(.elementor-motion-effects-element-type-background), .elementor-27438 .elementor-element.elementor-element-0090827 > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/savo.ae\/wp-content\/uploads\/2024\/02\/slide3.jpg\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-27438 .elementor-element.elementor-element-0090827::before, .elementor-27438 .elementor-element.elementor-element-0090827 > .elementor-background-video-container::before, .elementor-27438 .elementor-element.elementor-element-0090827 > .e-con-inner > .elementor-background-video-container::before, .elementor-27438 .elementor-element.elementor-element-0090827 > .elementor-background-slideshow::before, .elementor-27438 .elementor-element.elementor-element-0090827 > .e-con-inner > .elementor-background-slideshow::before, .elementor-27438 .elementor-element.elementor-element-0090827 > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{--background-overlay:'';background-color:var( --e-global-color-1c60969 );}.elementor-27438 .elementor-element.elementor-element-76a07c0{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:center;--align-items:center;--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27438 .elementor-element.elementor-element-786be21 .wd-button-wrapper a{background-color:var( --e-global-color-1c60969 );border-color:var( --e-global-color-1c60969 );color:var( --e-global-color-33d4c16 );}.elementor-27438 .elementor-element.elementor-element-c7811ad{--display:flex;--min-height:600px;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--align-items:center;--gap:30px 20px;--row-gap:30px;--column-gap:20px;--overlay-opacity:0.2;--padding-top:0px;--padding-bottom:0px;--padding-left:70px;--padding-right:70px;}.elementor-27438 .elementor-element.elementor-element-c7811ad:not(.elementor-motion-effects-element-type-background), .elementor-27438 .elementor-element.elementor-element-c7811ad > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/8.png\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-27438 .elementor-element.elementor-element-c7811ad::before, .elementor-27438 .elementor-element.elementor-element-c7811ad > .elementor-background-video-container::before, .elementor-27438 .elementor-element.elementor-element-c7811ad > .e-con-inner > .elementor-background-video-container::before, .elementor-27438 .elementor-element.elementor-element-c7811ad > .elementor-background-slideshow::before, .elementor-27438 .elementor-element.elementor-element-c7811ad > .e-con-inner > .elementor-background-slideshow::before, .elementor-27438 .elementor-element.elementor-element-c7811ad > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{--background-overlay:'';background-color:var( --e-global-color-1c60969 );}.elementor-27438 .elementor-element.elementor-element-73f7618{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27438 .elementor-element.elementor-element-5c4b7dd .wd-text-block{font-family:\"Playfair Display\", Sans-serif;font-size:65px;line-height:1.2em;color:var( --e-global-color-33d4c16 );}.elementor-27438 .elementor-element.elementor-element-5c4b7dd > .elementor-widget-container{margin:0px 0px 10px 0px;}.elementor-27438 .elementor-element.elementor-element-fae2a3a .wd-text-block{font-family:\"Playfair Display\", Sans-serif;font-size:65px;line-height:1.2em;color:var( --e-global-color-a053dca );}.elementor-27438 .elementor-element.elementor-element-fae2a3a > .elementor-widget-container{margin:0px 0px 40px 0px;}.elementor-27438 .elementor-element.elementor-element-4a74a9d .wd-button-wrapper a{background-color:var( --e-global-color-1c60969 );border-color:var( --e-global-color-1c60969 );color:var( --e-global-color-33d4c16 );}@media(max-width:1024px){.elementor-27438 .elementor-element.elementor-element-0090827{--min-height:500px;--overlay-opacity:0.1;--padding-top:0px;--padding-bottom:20px;--padding-left:50px;--padding-right:50px;}.elementor-27438 .elementor-element.elementor-element-76a07c0{--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27438 .elementor-element.elementor-element-c7811ad{--min-height:500px;--padding-top:0px;--padding-bottom:0px;--padding-left:50px;--padding-right:50px;}.elementor-27438 .elementor-element.elementor-element-73f7618{--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27438 .elementor-element.elementor-element-5c4b7dd .wd-text-block{font-size:42px;line-height:1.2em;}.elementor-27438 .elementor-element.elementor-element-5c4b7dd > .elementor-widget-container{margin:0px 0px 10px 0px;}.elementor-27438 .elementor-element.elementor-element-fae2a3a .wd-text-block{font-size:45px;line-height:1.2em;}.elementor-27438 .elementor-element.elementor-element-fae2a3a > .elementor-widget-container{margin:0px 0px 10px 0px;}}@media(max-width:768px){.elementor-27438 .elementor-element.elementor-element-0090827{--min-height:500px;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-end;--align-items:center;--overlay-opacity:0.1;--padding-top:0px;--padding-bottom:20px;--padding-left:30px;--padding-right:30px;}.elementor-27438 .elementor-element.elementor-element-c7811ad{--min-height:500px;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:center;--overlay-opacity:0.5;--padding-top:0px;--padding-bottom:0px;--padding-left:30px;--padding-right:30px;}.elementor-27438 .elementor-element.elementor-element-5c4b7dd .wd-text-block{font-size:38px;}.elementor-27438 .elementor-element.elementor-element-fae2a3a .wd-text-block{font-size:40px;}}@media(min-width:769px){.elementor-27438 .elementor-element.elementor-element-76a07c0{--width:46%;}.elementor-27438 .elementor-element.elementor-element-73f7618{--width:46%;}}@media(max-width:1024px) and (min-width:769px){.elementor-27438 .elementor-element.elementor-element-76a07c0{--width:54%;}.elementor-27438 .elementor-element.elementor-element-73f7618{--width:54%;}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"27438\" class=\"elementor elementor-27438\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0090827 e-con-full wd-section-stretch-content e-flex e-con e-parent\" data-id=\"0090827\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-76a07c0 e-con-full e-flex e-con e-child\" data-id=\"76a07c0\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-786be21 wd-animation-slide-from-bottom wd_delay_550 wd-animation-normal elementor-widget elementor-widget-wd_button\" data-id=\"786be21\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-large btn-color-custom btn-icon-pos-right\"  href=\"https:\/\/limegreen-opossum-178043.hostingersite.com\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\t\u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c7811ad e-con-full wd-section-stretch-content elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"c7811ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-73f7618 e-con-full e-flex e-con e-child\" data-id=\"73f7618\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5c4b7dd wd-animation-slide-from-bottom wd_delay_250 wd-animation-normal elementor-widget elementor-widget-wd_text_block\" data-id=\"5c4b7dd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>\u0633\u0627\u0641\u0648 \u2013 \u0627\u0644\u0646\u0645\u0637 \u0627\u0644\u062e\u0627\u0635 \u0628\u0643 \u060c<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fae2a3a wd-animation-slide-from-bottom wd_delay_400 wd-animation-normal elementor-widget elementor-widget-wd_text_block\" data-id=\"fae2a3a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>\u0627\u0644\u0628\u064a\u0627\u0646<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a74a9d wd-animation-slide-from-bottom wd_delay_550 wd-animation-normal elementor-widget elementor-widget-wd_button\" data-id=\"4a74a9d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-large btn-color-custom btn-icon-pos-right\"  href=\"https:\/\/limegreen-opossum-178043.hostingersite.com\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\t\u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"wd-slide-bg wd-fill\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"slide-27457\" class=\"wd-slide wd-carousel-item\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container wd-slide-container content-full-width wd-padding-off\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-slide-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>.elementor-27457 .elementor-element.elementor-element-bb09f0d{--display:flex;--min-height:600px;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--justify-content:center;--align-items:flex-end;--gap:30px 20px;--row-gap:30px;--column-gap:20px;--overlay-opacity:0.1;--padding-top:0px;--padding-bottom:50px;--padding-left:70px;--padding-right:70px;}.elementor-27457 .elementor-element.elementor-element-bb09f0d:not(.elementor-motion-effects-element-type-background), .elementor-27457 .elementor-element.elementor-element-bb09f0d > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-09-at-9.52.31-PM.jpeg\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-27457 .elementor-element.elementor-element-bb09f0d::before, .elementor-27457 .elementor-element.elementor-element-bb09f0d > .elementor-background-video-container::before, .elementor-27457 .elementor-element.elementor-element-bb09f0d > .e-con-inner > .elementor-background-video-container::before, .elementor-27457 .elementor-element.elementor-element-bb09f0d > .elementor-background-slideshow::before, .elementor-27457 .elementor-element.elementor-element-bb09f0d > .e-con-inner > .elementor-background-slideshow::before, .elementor-27457 .elementor-element.elementor-element-bb09f0d > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{--background-overlay:'';background-color:var( --e-global-color-1c60969 );}.elementor-27457 .elementor-element.elementor-element-a944c70{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:center;--align-items:center;--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27457 .elementor-element.elementor-element-c1e6d5a .wd-button-wrapper a{background-color:var( --e-global-color-1c60969 );border-color:var( --e-global-color-1c60969 );color:var( --e-global-color-33d4c16 );}.elementor-27457 .elementor-element.elementor-element-74d88de{--display:flex;--min-height:600px;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--align-items:center;--gap:30px 20px;--row-gap:30px;--column-gap:20px;--overlay-opacity:0.3;--padding-top:0px;--padding-bottom:0px;--padding-left:70px;--padding-right:70px;}.elementor-27457 .elementor-element.elementor-element-74d88de:not(.elementor-motion-effects-element-type-background), .elementor-27457 .elementor-element.elementor-element-74d88de > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/3.png\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-27457 .elementor-element.elementor-element-74d88de::before, .elementor-27457 .elementor-element.elementor-element-74d88de > .elementor-background-video-container::before, .elementor-27457 .elementor-element.elementor-element-74d88de > .e-con-inner > .elementor-background-video-container::before, .elementor-27457 .elementor-element.elementor-element-74d88de > .elementor-background-slideshow::before, .elementor-27457 .elementor-element.elementor-element-74d88de > .e-con-inner > .elementor-background-slideshow::before, .elementor-27457 .elementor-element.elementor-element-74d88de > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{--background-overlay:'';background-color:var( --e-global-color-1c60969 );}.elementor-27457 .elementor-element.elementor-element-2c5b471{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27457 .elementor-element.elementor-element-e20c8d7 .wd-text-block{font-family:\"Playfair Display\", Sans-serif;font-size:65px;line-height:1.2em;color:var( --e-global-color-33d4c16 );}.elementor-27457 .elementor-element.elementor-element-e20c8d7 > .elementor-widget-container{margin:0px 0px 10px 0px;}.elementor-27457 .elementor-element.elementor-element-aad22ec .wd-text-block{font-family:\"Playfair Display\", Sans-serif;font-size:65px;line-height:1.2em;color:var( --e-global-color-a053dca );}.elementor-27457 .elementor-element.elementor-element-aad22ec > .elementor-widget-container{margin:0px 0px 40px 0px;}.elementor-27457 .elementor-element.elementor-element-595e942 .wd-button-wrapper a{background-color:var( --e-global-color-1c60969 );border-color:var( --e-global-color-1c60969 );color:var( --e-global-color-33d4c16 );}@media(max-width:1024px){.elementor-27457 .elementor-element.elementor-element-bb09f0d{--min-height:500px;--padding-top:0px;--padding-bottom:30px;--padding-left:50px;--padding-right:50px;}.elementor-27457 .elementor-element.elementor-element-a944c70{--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27457 .elementor-element.elementor-element-74d88de{--min-height:500px;--padding-top:0px;--padding-bottom:0px;--padding-left:50px;--padding-right:50px;}.elementor-27457 .elementor-element.elementor-element-2c5b471{--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27457 .elementor-element.elementor-element-e20c8d7 .wd-text-block{font-size:42px;line-height:1.2em;}.elementor-27457 .elementor-element.elementor-element-e20c8d7 > .elementor-widget-container{margin:0px 0px 10px 0px;}.elementor-27457 .elementor-element.elementor-element-aad22ec .wd-text-block{font-size:45px;line-height:1.2em;}.elementor-27457 .elementor-element.elementor-element-aad22ec > .elementor-widget-container{margin:0px 0px 10px 0px;}}@media(max-width:768px){.elementor-27457 .elementor-element.elementor-element-bb09f0d{--min-height:500px;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-end;--overlay-opacity:0.1;--padding-top:0px;--padding-bottom:20px;--padding-left:30px;--padding-right:30px;}.elementor-27457 .elementor-element.elementor-element-bb09f0d:not(.elementor-motion-effects-element-type-background), .elementor-27457 .elementor-element.elementor-element-bb09f0d > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-position:center center;}.elementor-27457 .elementor-element.elementor-element-74d88de{--min-height:500px;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:center;--overlay-opacity:0.5;--padding-top:0px;--padding-bottom:0px;--padding-left:30px;--padding-right:30px;}.elementor-27457 .elementor-element.elementor-element-e20c8d7 .wd-text-block{font-size:38px;}.elementor-27457 .elementor-element.elementor-element-aad22ec .wd-text-block{font-size:40px;}}@media(min-width:769px){.elementor-27457 .elementor-element.elementor-element-a944c70{--width:46%;}.elementor-27457 .elementor-element.elementor-element-2c5b471{--width:46%;}}@media(max-width:1024px) and (min-width:769px){.elementor-27457 .elementor-element.elementor-element-a944c70{--width:54%;}.elementor-27457 .elementor-element.elementor-element-2c5b471{--width:54%;}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"27457\" class=\"elementor elementor-27457\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bb09f0d e-con-full wd-section-stretch-content e-flex e-con e-parent\" data-id=\"bb09f0d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-a944c70 e-con-full e-flex e-con e-child\" data-id=\"a944c70\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c1e6d5a wd-animation-slide-from-bottom wd_delay_550 wd-animation-normal elementor-widget elementor-widget-wd_button\" data-id=\"c1e6d5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-large btn-color-custom btn-icon-pos-right\"  href=\"https:\/\/limegreen-opossum-178043.hostingersite.com\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\t\u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-74d88de e-con-full wd-section-stretch-content elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"74d88de\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-2c5b471 e-con-full e-flex e-con e-child\" data-id=\"2c5b471\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e20c8d7 wd-animation-slide-from-bottom wd_delay_250 wd-animation-normal elementor-widget elementor-widget-wd_text_block\" data-id=\"e20c8d7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>\u062e\u0637\u0648\u0629 \u0627\u0644\u0649 \u0646\u0645\u0637\u00a0<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aad22ec wd-animation-slide-from-bottom wd_delay_400 wd-animation-normal elementor-widget elementor-widget-wd_text_block\" data-id=\"aad22ec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>\u0645\u0639 \u0633\u0627\u0641\u0648<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-595e942 wd-animation-slide-from-bottom wd_delay_550 wd-animation-normal elementor-widget elementor-widget-wd_button\" data-id=\"595e942\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-large btn-color-custom btn-icon-pos-right\"  href=\"https:\/\/limegreen-opossum-178043.hostingersite.com\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\t\u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"wd-slide-bg wd-fill\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div id=\"slide-27463\" class=\"wd-slide wd-carousel-item\" >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"container wd-slide-container content-full-width wd-padding-off\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-slide-inner\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<style>.elementor-27463 .elementor-element.elementor-element-573bccb{--display:flex;--min-height:600px;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--justify-content:center;--align-items:flex-end;--gap:30px 20px;--row-gap:30px;--column-gap:20px;--overlay-opacity:0.1;--padding-top:0px;--padding-bottom:50px;--padding-left:70px;--padding-right:70px;}.elementor-27463 .elementor-element.elementor-element-573bccb:not(.elementor-motion-effects-element-type-background), .elementor-27463 .elementor-element.elementor-element-573bccb > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/savo.ae\/wp-content\/uploads\/2024\/02\/slide2.jpg\");background-position:top center;background-repeat:no-repeat;background-size:cover;}.elementor-27463 .elementor-element.elementor-element-573bccb::before, .elementor-27463 .elementor-element.elementor-element-573bccb > .elementor-background-video-container::before, .elementor-27463 .elementor-element.elementor-element-573bccb > .e-con-inner > .elementor-background-video-container::before, .elementor-27463 .elementor-element.elementor-element-573bccb > .elementor-background-slideshow::before, .elementor-27463 .elementor-element.elementor-element-573bccb > .e-con-inner > .elementor-background-slideshow::before, .elementor-27463 .elementor-element.elementor-element-573bccb > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{--background-overlay:'';background-color:var( --e-global-color-1c60969 );}.elementor-27463 .elementor-element.elementor-element-b4a787a{--display:flex;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:center;--align-items:center;--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27463 .elementor-element.elementor-element-acc9d9f .wd-button-wrapper a{background-color:var( --e-global-color-1c60969 );border-color:var( --e-global-color-1c60969 );color:var( --e-global-color-33d4c16 );}.elementor-27463 .elementor-element.elementor-element-83cb14f{--display:flex;--min-height:600px;--flex-direction:row;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:100%;--container-widget-flex-grow:1;--container-widget-align-self:stretch;--flex-wrap-mobile:wrap;--align-items:center;--gap:30px 20px;--row-gap:30px;--column-gap:20px;--overlay-opacity:0.3;--padding-top:0px;--padding-bottom:0px;--padding-left:70px;--padding-right:70px;}.elementor-27463 .elementor-element.elementor-element-83cb14f:not(.elementor-motion-effects-element-type-background), .elementor-27463 .elementor-element.elementor-element-83cb14f > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/38.png\");background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-27463 .elementor-element.elementor-element-83cb14f::before, .elementor-27463 .elementor-element.elementor-element-83cb14f > .elementor-background-video-container::before, .elementor-27463 .elementor-element.elementor-element-83cb14f > .e-con-inner > .elementor-background-video-container::before, .elementor-27463 .elementor-element.elementor-element-83cb14f > .elementor-background-slideshow::before, .elementor-27463 .elementor-element.elementor-element-83cb14f > .e-con-inner > .elementor-background-slideshow::before, .elementor-27463 .elementor-element.elementor-element-83cb14f > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{--background-overlay:'';background-color:var( --e-global-color-1c60969 );}.elementor-27463 .elementor-element.elementor-element-57403ac{--display:flex;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27463 .elementor-element.elementor-element-0c2811b .wd-text-block{font-family:\"Playfair Display\", Sans-serif;font-size:65px;line-height:1.2em;color:var( --e-global-color-33d4c16 );}.elementor-27463 .elementor-element.elementor-element-0c2811b > .elementor-widget-container{margin:0px 0px 10px 0px;}.elementor-27463 .elementor-element.elementor-element-bb209dc .wd-text-block{font-family:\"Playfair Display\", Sans-serif;font-size:65px;line-height:1.2em;color:var( --e-global-color-a053dca );}.elementor-27463 .elementor-element.elementor-element-bb209dc > .elementor-widget-container{margin:0px 0px 40px 0px;}.elementor-27463 .elementor-element.elementor-element-850bbc6 .wd-button-wrapper a{background-color:var( --e-global-color-1c60969 );border-color:var( --e-global-color-1c60969 );color:var( --e-global-color-33d4c16 );}@media(max-width:1024px){.elementor-27463 .elementor-element.elementor-element-573bccb{--min-height:500px;--overlay-opacity:0.1;--padding-top:0px;--padding-bottom:20px;--padding-left:50px;--padding-right:50px;}.elementor-27463 .elementor-element.elementor-element-b4a787a{--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27463 .elementor-element.elementor-element-83cb14f{--min-height:500px;--padding-top:0px;--padding-bottom:0px;--padding-left:50px;--padding-right:50px;}.elementor-27463 .elementor-element.elementor-element-57403ac{--gap:0px 0px;--row-gap:0px;--column-gap:0px;}.elementor-27463 .elementor-element.elementor-element-0c2811b .wd-text-block{font-size:42px;line-height:1.2em;}.elementor-27463 .elementor-element.elementor-element-0c2811b > .elementor-widget-container{margin:0px 0px 10px 0px;}.elementor-27463 .elementor-element.elementor-element-bb209dc .wd-text-block{font-size:45px;line-height:1.2em;}.elementor-27463 .elementor-element.elementor-element-bb209dc > .elementor-widget-container{margin:0px 0px 10px 0px;}}@media(max-width:768px){.elementor-27463 .elementor-element.elementor-element-573bccb{--min-height:500px;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:flex-end;--align-items:center;--overlay-opacity:0.1;--padding-top:0px;--padding-bottom:20px;--padding-left:30px;--padding-right:30px;}.elementor-27463 .elementor-element.elementor-element-573bccb:not(.elementor-motion-effects-element-type-background), .elementor-27463 .elementor-element.elementor-element-573bccb > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-position:center center;}.elementor-27463 .elementor-element.elementor-element-83cb14f{--min-height:500px;--flex-direction:column;--container-widget-width:100%;--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:center;--overlay-opacity:0.5;--padding-top:0px;--padding-bottom:0px;--padding-left:30px;--padding-right:30px;}.elementor-27463 .elementor-element.elementor-element-0c2811b .wd-text-block{font-size:38px;}.elementor-27463 .elementor-element.elementor-element-bb209dc .wd-text-block{font-size:40px;}}@media(min-width:769px){.elementor-27463 .elementor-element.elementor-element-b4a787a{--width:46%;}.elementor-27463 .elementor-element.elementor-element-57403ac{--width:46%;}}@media(max-width:1024px) and (min-width:769px){.elementor-27463 .elementor-element.elementor-element-b4a787a{--width:54%;}.elementor-27463 .elementor-element.elementor-element-57403ac{--width:54%;}}<\/style>\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"27463\" class=\"elementor elementor-27463\">\n\t\t\t\t<div class=\"elementor-element elementor-element-573bccb e-con-full wd-section-stretch-content e-flex e-con e-parent\" data-id=\"573bccb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-b4a787a e-con-full e-flex e-con e-child\" data-id=\"b4a787a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acc9d9f wd-animation-slide-from-bottom wd_delay_550 wd-animation-normal elementor-widget elementor-widget-wd_button\" data-id=\"acc9d9f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-large btn-color-custom btn-icon-pos-right\"  href=\"https:\/\/limegreen-opossum-178043.hostingersite.com\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\t\u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-83cb14f e-con-full wd-section-stretch-content elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-parent\" data-id=\"83cb14f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-57403ac e-con-full e-flex e-con e-child\" data-id=\"57403ac\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0c2811b wd-animation-slide-from-bottom wd_delay_250 wd-animation-normal elementor-widget elementor-widget-wd_text_block\" data-id=\"0c2811b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>\u0623\u0632\u064a\u0627\u0621 \u0644\u0643\u0644\u00a0<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bb209dc wd-animation-slide-from-bottom wd_delay_400 wd-animation-normal elementor-widget elementor-widget-wd_text_block\" data-id=\"bb209dc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-left\">\n\t\t\t\n\t\t\t<p>\u0642\u062f\u0645 \u0625\u0644\u0649 \u0627\u0644\u0623\u0645\u0627\u0645<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-850bbc6 wd-animation-slide-from-bottom wd_delay_550 wd-animation-normal elementor-widget elementor-widget-wd_button\" data-id=\"850bbc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-left\" >\n\t\t\t<a class=\"btn btn-style-default btn-shape-rectangle btn-size-large btn-color-custom btn-icon-pos-right\"  href=\"https:\/\/limegreen-opossum-178043.hostingersite.com\/shop\/\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\t\u062a\u0633\u0648\u0642 \u0627\u0644\u0622\u0646\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"wd-slide-bg wd-fill\"><\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-slider-arrows wd-custom-style wd-style-1 wd-pos-sep color-scheme-light\">\n\t\t\t\t\t\t<div class=\"wd-btn-arrow wd-prev\">\n\t\t\t\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap wd-slider-pagin wd-custom-style wd-style-shape-1 text-center color-scheme-light\">\n\t\t\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7be27a2 e-con-full wd-section-stretch-content e-flex e-con e-parent\" data-id=\"7be27a2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-ed9a817 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"ed9a817\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e0bba4e elementor-hidden-tablet elementor-widget elementor-widget-wd_text_block\" data-id=\"e0bba4e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-center\">\n\t\t\t\n\t\t\t<p>\u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062c\u062f\u064a\u062f\u0629<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dfc977a wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"dfc977a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h3 class=\"woodmart-title-container title wd-fontsize-xxl\">\u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062c\u062f\u064a\u062f\u0629<\/h3> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f3a7259 elementor-hidden-desktop elementor-hidden-tablet wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"f3a7259\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div id=\"carousel-673\" class=\"wd-carousel-container  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-speed=\"5000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-autoheight=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28138 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"1\" data-id=\"28138\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-6\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img fetchpriority=\"high\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-6\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-6\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28138\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28138\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Aurea&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28138\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-6\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28138\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28138\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28138\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-6\/\">Aurea<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28287 status-publish instock product_cat-girls product_cat-shoes-girls has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"2\" data-id=\"28287\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/avelin\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/avelin\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/avelin\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28287\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28287\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Avelin&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28287\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/avelin\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28287\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28287\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28287\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/avelin\/\">Avelin<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/girls\/\" rel=\"tag\">\u0627\u0644\u0628\u0646\u0627\u062a<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/girls\/shoes-girls\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28421 status-publish last instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"3\" data-id=\"28421\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/brell\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/brell\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/brell\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28421\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28421\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Brell&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28421\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/brell\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28421\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28421\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28421\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/brell\/\">Brell<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28329 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"4\" data-id=\"28329\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/calvix\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/calvix\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/calvix\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28329\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28329\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Calvix&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28329\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/calvix\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28329\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28329\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28329\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/calvix\/\">Calvix<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28308 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"5\" data-id=\"28308\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-13\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-13\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-13\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28308\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28308\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Celest&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28308\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-13\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28308\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28308\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28308\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-13\/\">Celest<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28358 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"6\" data-id=\"28358\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/elvane\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/elvane\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/elvane\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28358\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28358\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Elvane&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28358\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/elvane\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28358\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28358\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28358\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/elvane\/\">Elvane<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>143&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 143&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28051 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"7\" data-id=\"28051\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28051\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28051\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Elvyn&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28051\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28051\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28051\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28051\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product\/\">Elvyn<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28248 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"8\" data-id=\"28248\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-11\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-11\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-11\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28248\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28248\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Elysia&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28248\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-11\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28248\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28248\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28248\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-11\/\">Elysia<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 159&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28298 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"9\" data-id=\"28298\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/evara\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/evara\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/evara\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28298\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28298\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Evara&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28298\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/evara\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28298\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28298\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28298\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/evara\/\">Evara<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>149&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 149&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>97&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 97&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28090 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"10\" data-id=\"28090\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-3\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-3\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-3\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28090\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28090\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Femme&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28090\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-3\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28090\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28090\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28090\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-3\/\">Femme<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28322 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"11\" data-id=\"28322\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/helqon\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/helqon\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/helqon\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28322\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28322\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Helqon&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28322\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/helqon\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28322\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28322\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28322\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/helqon\/\">Helqon<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28403 status-publish first instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"12\" data-id=\"28403\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28403\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28403\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Hoppo&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28403\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28403\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28403\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28403\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\">Hoppo<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28066 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"13\" data-id=\"28066\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28066\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28066\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Isola&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28066\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28066\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28066\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28066\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\">Isola<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28375 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"14\" data-id=\"28375\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133.png 1524w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138.png 1024w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28375\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28375\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Kaviro&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28375\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28375\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28375\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28375\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\">Kaviro<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>187&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 187&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>149&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 149&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28415 status-publish last instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"15\" data-id=\"28415\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28415\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28415\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Kidoo&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28415\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28415\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28415\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28415\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\">Kidoo<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28383 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"16\" data-id=\"28383\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-801x800.png 801w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-768x767.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123.png 1497w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28383\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28383\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lumexi&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28383\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28383\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28383\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28383\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\">Lumexi<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>143&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 143&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28058 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable product-type-variable\" data-loop=\"17\" data-id=\"28058\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28058\" data-quantity=\"1\" class=\"button product_type_variable add-to-cart-loop\" data-product_id=\"28058\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lunara&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28058\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28058\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28058\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28058\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\">Lunara<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28238 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"18\" data-id=\"28238\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28238\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28238\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lushat&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28238\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/lushat\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28238\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28238\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28238\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\">Lushat<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28023 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"19\" data-id=\"28023\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28023\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28023\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Luxe&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28023\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28023\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28023\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28023\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\">Luxe<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28264 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"20\" data-id=\"28264\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28264\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28264\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Mirava&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28264\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/mirava\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28264\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28264\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28264\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\">Mirava<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-99df70e elementor-hidden-mobile wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"99df70e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div id=\"carousel-811\" class=\"wd-carousel-container  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-speed=\"5000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-autoheight=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28138 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"1\" data-id=\"28138\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-6\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357395-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-6\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357399-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28138\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-6\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28138\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28138\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-6\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28138\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28138\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Aurea&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28138\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-6\/\">Aurea<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28287 status-publish instock product_cat-girls product_cat-shoes-girls has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"2\" data-id=\"28287\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/avelin\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357275-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/avelin\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357270-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28287\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/avelin\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28287\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28287\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/avelin\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28287\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28287\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Avelin&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28287\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/avelin\/\">Avelin<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/girls\/\" rel=\"tag\">\u0627\u0644\u0628\u0646\u0627\u062a<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/girls\/shoes-girls\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28421 status-publish last instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"3\" data-id=\"28421\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/brell\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357441-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/brell\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357446-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28421\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/brell\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28421\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28421\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/brell\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28421\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28421\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Brell&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28421\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/brell\/\">Brell<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28329 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"4\" data-id=\"28329\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/calvix\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357219-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/calvix\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357218-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28329\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/calvix\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28329\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28329\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/calvix\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28329\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28329\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Calvix&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28329\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/calvix\/\">Calvix<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28308 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"5\" data-id=\"28308\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-13\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357250-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-13\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357248-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28308\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-13\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28308\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28308\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-13\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28308\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28308\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Celest&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28308\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-13\/\">Celest<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28358 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"6\" data-id=\"28358\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/elvane\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357149-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/elvane\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357151-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28358\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/elvane\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28358\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28358\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/elvane\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28358\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28358\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Elvane&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28358\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/elvane\/\">Elvane<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>143&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 143&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28051 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"7\" data-id=\"28051\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357534-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357538-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28051\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28051\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28051\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28051\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28051\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Elvyn&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28051\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product\/\">Elvyn<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28248 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"8\" data-id=\"28248\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-11\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357325-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-11\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357328-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28248\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-11\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28248\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28248\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-11\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28248\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28248\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Elysia&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28248\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-11\/\">Elysia<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 159&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28298 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"9\" data-id=\"28298\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/evara\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357255-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/evara\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357259-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28298\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/evara\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28298\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28298\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/evara\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28298\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28298\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Evara&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28298\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/evara\/\">Evara<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>149&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 149&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>97&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 97&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28090 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"10\" data-id=\"28090\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-3\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357492-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-3\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357501-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28090\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-3\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28090\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28090\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-3\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28090\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28090\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Femme&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28090\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-3\/\">Femme<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28322 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"11\" data-id=\"28322\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/helqon\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357234-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/helqon\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357229-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28322\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/helqon\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28322\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28322\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/helqon\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28322\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28322\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Helqon&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28322\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/helqon\/\">Helqon<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28403 status-publish first instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"12\" data-id=\"28403\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357461-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357457-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28403\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28403\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28403\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28403\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28403\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Hoppo&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28403\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/hoppo\/\">Hoppo<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28066 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"13\" data-id=\"28066\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28066\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28066\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28066\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28066\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28066\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Isola&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28066\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\">Isola<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28375 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"14\" data-id=\"28375\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138.png 1024w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-500x500.png 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28375\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28375\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28375\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28375\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28375\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Kaviro&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28375\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\">Kaviro<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>187&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 187&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>149&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 149&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28415 status-publish last instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"15\" data-id=\"28415\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28415\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28415\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28415\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28415\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28415\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Kidoo&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28415\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\">Kidoo<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28383 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"16\" data-id=\"28383\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28383\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28383\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28383\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28383\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28383\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lumexi&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28383\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\">Lumexi<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>143&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 143&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28058 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable product-type-variable\" data-loop=\"17\" data-id=\"28058\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28058\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28058\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28058\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28058\" data-quantity=\"1\" class=\"button product_type_variable add-to-cart-loop\" data-product_id=\"28058\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lunara&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28058\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\">Lunara<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28238 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"18\" data-id=\"28238\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28238\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/lushat\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28238\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28238\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28238\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28238\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lushat&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28238\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\">Lushat<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28023 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"19\" data-id=\"28023\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28023\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28023\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28023\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28023\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28023\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Luxe&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28023\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\">Luxe<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28264 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"20\" data-id=\"28264\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28264\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/mirava\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28264\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28264\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28264\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28264\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Mirava&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28264\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\">Mirava<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-47c44f7 wd-section-stretch-content e-con-full e-flex e-con e-parent\" data-id=\"47c44f7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad2abbd wd-width-100 wd-nav-accordion-mb-on elementor-widget elementor-widget-wd_product_categories\" data-id=\"ad2abbd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_product_categories.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-cats-element\">\n\t\t\t\t\t<div class=\"wd-grid-g wd-cats products woocommerce columns-3 elements-grid\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:1;--wd-gap-lg:10px;--wd-gap-sm:20px;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-alt without-product-count wd-with-subcat product-category product first\" data-loop=\"1\">\n\t\n\t<div class=\"wrapp-category\">\n\t\t<div class=\"category-image-wrapp\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" class=\"category-image\" aria-label=\"Category image\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2024\/02\/women1-450x600.jpg\" class=\"attachment-450x600 size-450x600\" alt=\"\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\t\u0627\u0644\u0645\u0631\u0623\u0629 <mark class=\"count\">(27)<\/mark>\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" class=\"category-link wd-fill\" aria-label=\"Product category women\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-alt without-product-count wd-with-subcat product-category product\" data-loop=\"2\">\n\t\n\t<div class=\"wrapp-category\">\n\t\t<div class=\"category-image-wrapp\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/men\/\" class=\"category-image\" aria-label=\"Category image\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-09-at-9.53.50-PM-450x600.jpeg\" class=\"attachment-450x600 size-450x600\" alt=\"\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\t\u0627\u0644\u0631\u062c\u0644\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/men\/\" class=\"category-link wd-fill\" aria-label=\"Product category men\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-alt without-product-count wd-with-subcat product-category product\" data-loop=\"3\">\n\t\n\t<div class=\"wrapp-category\">\n\t\t<div class=\"category-image-wrapp\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/girls\/\" class=\"category-image\" aria-label=\"Category image\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2024\/02\/kids1-450x600.jpg\" class=\"attachment-450x600 size-450x600\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2024\/02\/kids1-450x600.jpg 450w, https:\/\/savo.ae\/wp-content\/uploads\/2024\/02\/kids1-8x12.jpg 8w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\t\u0627\u0644\u0628\u0646\u0627\u062a <mark class=\"count\">(1)<\/mark>\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/girls\/\" class=\"category-link wd-fill\" aria-label=\"Product category girls\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-06afc8a wd-width-100 wd-nav-accordion-mb-on elementor-widget elementor-widget-wd_product_categories\" data-id=\"06afc8a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_product_categories.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t<div class=\"wd-cats-element\">\n\t\t\t\t\t<div class=\"wd-grid-g wd-cats products woocommerce columns-3 elements-grid\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:1;--wd-gap-lg:10px;--wd-gap-sm:20px;\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-alt without-product-count wd-with-subcat product-category product first\" data-loop=\"1\">\n\t\n\t<div class=\"wrapp-category\">\n\t\t<div class=\"category-image-wrapp\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" class=\"category-image\" aria-label=\"Category image\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-09-at-4.55.54-PM-450x600.jpeg\" class=\"attachment-450x600 size-450x600\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-09-at-4.55.54-PM-450x600.jpeg 450w, https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/WhatsApp-Image-2025-07-09-at-4.55.54-PM-9x12.jpeg 9w\" sizes=\"(max-width: 450px) 100vw, 450px\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\t\u0627\u0644\u0623\u0648\u0644\u0627\u062f <mark class=\"count\">(4)<\/mark>\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" class=\"category-link wd-fill\" aria-label=\"Product category boys\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n<div class=\"wd-col category-grid-item wd-cat cat-design-alt without-product-count wd-with-subcat product-category product\" data-loop=\"2\">\n\t\n\t<div class=\"wrapp-category\">\n\t\t<div class=\"category-image-wrapp\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/perfume-and-accessories\/\" class=\"category-image\" aria-label=\"Category image\">\n\t\t\t\t\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"450\" height=\"600\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2025\/07\/savo-7-450x600.png\" class=\"attachment-450x600 size-450x600\" alt=\"\" \/>\t\t\t<\/a>\n\t\t<\/div>\n\t\t<div class=\"hover-mask\">\n\t\t\t<h3 class=\"wd-entities-title\">\n\t\t\t\t\u0627\u0644\u0639\u0637\u0648\u0631 \u0648\u0627\u0644\u0627\u0643\u0633\u0633\u0648\u0627\u0631\u0627\u062a\t\t\t<\/h3>\n\n\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/perfume-and-accessories\/\" class=\"category-link wd-fill\" aria-label=\"Product category perfume-and-accessories\"><\/a>\n\t\t\t<\/div>\n\n\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d75b6ab e-con-full wd-section-stretch-content e-flex e-con e-parent\" data-id=\"d75b6ab\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d1481b8 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"d1481b8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87554d0 elementor-hidden-tablet elementor-widget elementor-widget-wd_text_block\" data-id=\"87554d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_text_block.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"wd-text-block reset-last-child text-center\">\n\t\t\t\n\t\t\t<p>\u0627\u0644\u0645\u0646\u062a\u062c\u0627\u062a \u0627\u0644\u062c\u062f\u064a\u062f\u0629<\/p>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9bb1559 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"9bb1559\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h3 class=\"woodmart-title-container title wd-fontsize-xxl\">\u0627\u0644\u0627\u0641\u0636\u0644 \u0645\u0628\u064a\u0639\u0627<\/h3> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-185fd80 elementor-hidden-desktop elementor-hidden-tablet wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"185fd80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div id=\"carousel-369\" class=\"wd-carousel-container  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-speed=\"5000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-autoheight=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28077 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"1\" data-id=\"28077\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-2\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-2\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28077\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28077\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Zyra&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28077\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28077\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28077\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28077\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-2\/\">Zyra<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28350 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"2\" data-id=\"28350\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/vylor\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/vylor\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/vylor\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28350\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28350\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Vylor&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28350\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/vylor\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28350\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28350\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28350\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/vylor\/\">Vylor<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>175&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 175&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28031 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"3\" data-id=\"28031\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28031\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28031\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Velvet&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28031\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28031\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28031\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28031\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\">Velvet<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28115 status-publish first instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"4\" data-id=\"28115\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28115\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28115\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Velora&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28115\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28115\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28115\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28115\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\">Velora<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28128 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"5\" data-id=\"28128\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-5\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-5\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-5\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28128\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28128\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Twilight&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28128\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-5\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28128\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28128\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28128\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-5\/\">Twilight<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>217&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 217&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>141&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 141&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28148 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"6\" data-id=\"28148\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-7\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-7\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-7\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28148\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28148\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Sorelle&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28148\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-7\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28148\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28148\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28148\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-7\/\">Sorelle<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28222 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"7\" data-id=\"28222\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-10\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-10\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-10\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28222\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28222\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Serene&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28222\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-10\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28222\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28222\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28222\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-10\/\">Serene<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28276 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"8\" data-id=\"28276\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-12\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-12\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-12\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28276\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28276\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Ravelle&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28276\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-12\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28276\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28276\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28276\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-12\/\">Ravelle<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>149&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 149&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>97&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 97&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28394 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"9\" data-id=\"28394\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-15\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-15\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-15\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28394\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28394\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Quvex&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28394\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-15\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28394\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28394\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28394\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-15\/\">Quvex<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>169&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 169&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>135&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 135&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28202 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"10\" data-id=\"28202\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-9\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-9\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-9\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28202\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28202\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Opal&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28202\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28202\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28202\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28202\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-9\/\">Opal<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 159&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28161 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"11\" data-id=\"28161\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-8\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-8\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-8\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28161\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28161\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Nyxen&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28161\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-8\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28161\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28161\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28161\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-8\/\">Nyxen<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28121 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"12\" data-id=\"28121\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-4\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-4\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-4\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28121\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28121\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Noirelle&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28121\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-4\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28121\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28121\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28121\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-4\/\">Noirelle<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>217&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 217&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>141&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 141&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28264 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"13\" data-id=\"28264\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28264\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28264\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Mirava&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28264\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/mirava\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28264\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28264\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28264\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\">Mirava<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28023 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"14\" data-id=\"28023\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28023\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28023\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Luxe&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28023\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28023\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28023\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28023\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\">Luxe<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28238 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"15\" data-id=\"28238\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28238\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28238\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lushat&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28238\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/lushat\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28238\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28238\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28238\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\">Lushat<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28058 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable product-type-variable\" data-loop=\"16\" data-id=\"28058\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28058\" data-quantity=\"1\" class=\"button product_type_variable add-to-cart-loop\" data-product_id=\"28058\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lunara&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28058\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28058\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28058\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28058\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\">Lunara<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28383 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"17\" data-id=\"28383\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-801x800.png 801w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-768x767.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123.png 1497w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28383\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28383\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lumexi&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28383\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28383\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28383\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28383\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\">Lumexi<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>143&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 143&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28415 status-publish instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"18\" data-id=\"28415\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28415\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28415\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Kidoo&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28415\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28415\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28415\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28415\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\">Kidoo<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28375 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"19\" data-id=\"28375\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133.png 1524w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138.png 1024w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28375\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28375\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Kaviro&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28375\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28375\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28375\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28375\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\">Kaviro<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>187&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 187&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>149&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 149&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-icons product-grid-item product type-product post-28066 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"20\" data-id=\"28066\">\n\t\n\t<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-500x500.png\" class=\"attachment-500x500 size-500x500\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-500x500.png 500w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-1536x1536.png 1536w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510.png 1792w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\n\t\t<div class=\"wrapp-buttons\">\n\t\t\t<div class=\"wd-buttons\">\n\t\t\t\t<div class=\"wd-add-btn wd-action-btn wd-style-icon wd-add-cart-icon\"><a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28066\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28066\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Isola&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28066\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28066\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28066\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28066\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div>\n\t\t\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\">Isola<\/a><\/h3>\t\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\t\n\t\t\n\t\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1e3837b elementor-hidden-mobile wd-width-100 elementor-widget elementor-widget-wd_products\" data-id=\"1e3837b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div id=\"carousel-614\" class=\"wd-carousel-container  wd-products-element wd-products products\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t<div class=\"wd-carousel-inner\">\n\t\t\t\t\t<div class=\"wd-carousel wd-grid\" data-speed=\"5000\" data-wrap=\"yes\" data-autoplay=\"yes\" data-autoheight=\"yes\" data-scroll_per_page=\"yes\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:2;--wd-gap-lg:20px;--wd-gap-sm:10px;\">\n\t\t\t\t\t\t<div class=\"wd-carousel-wrap\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28077 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"1\" data-id=\"28077\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-2\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357506-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-2\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357505-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28077\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-2\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28077\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28077\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-2\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28077\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28077\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Zyra&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28077\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-2\/\">Zyra<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28350 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"2\" data-id=\"28350\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/vylor\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357184-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/vylor\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357185-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28350\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/vylor\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28350\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28350\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/vylor\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28350\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28350\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Vylor&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28350\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/vylor\/\">Vylor<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>175&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 175&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28031 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"3\" data-id=\"28031\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357559-2-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357557-2-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28031\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28031\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28031\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28031\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28031\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Velvet&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28031\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/velvet-bloom\/\">Velvet<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28115 status-publish first instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"4\" data-id=\"28115\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357476-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357475-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28115\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28115\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28115\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28115\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28115\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Velora&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28115\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/bliss-walk\/\">Velora<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28128 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"5\" data-id=\"28128\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-5\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357401-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-5\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357405-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28128\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-5\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28128\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28128\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-5\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28128\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28128\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Twilight&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28128\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-5\/\">Twilight<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>217&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 217&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>141&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 141&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28148 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"6\" data-id=\"28148\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-7\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357391-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-7\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357387-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28148\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-7\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28148\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28148\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-7\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28148\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28148\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Sorelle&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28148\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-7\/\">Sorelle<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28222 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"7\" data-id=\"28222\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-10\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357340-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-10\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357341-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28222\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-10\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28222\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28222\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-10\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28222\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28222\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Serene&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28222\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-10\/\">Serene<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28276 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"8\" data-id=\"28276\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-12\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357204-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-12\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357206-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28276\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-12\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28276\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28276\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-12\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28276\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28276\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Ravelle&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28276\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-12\/\">Ravelle<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>149&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 149&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>97&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 97&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28394 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"9\" data-id=\"28394\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-15\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357100-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-15\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357102-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28394\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-15\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28394\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28394\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-15\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28394\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28394\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Quvex&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28394\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-15\/\">Quvex<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>169&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 169&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>135&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 135&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28202 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"10\" data-id=\"28202\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-9\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357361-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-9\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357357-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28202\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-9\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28202\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28202\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-9\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28202\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28202\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Opal&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28202\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-9\/\">Opal<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 159&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28161 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"11\" data-id=\"28161\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-8\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357373-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-8\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357375-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28161\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-8\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28161\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28161\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-8\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28161\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28161\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Nyxen&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28161\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-8\/\">Nyxen<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28121 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"12\" data-id=\"28121\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-4\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357429-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-4\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357428-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28121\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/product-4\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28121\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28121\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/product-4\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28121\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28121\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Noirelle&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28121\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/product-4\/\">Noirelle<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>217&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 217&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>141&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 141&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28264 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"13\" data-id=\"28264\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357294-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357291-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28264\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/mirava\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28264\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28264\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28264\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28264\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Mirava&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28264\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/mirava\/\">Mirava<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28023 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"14\" data-id=\"28023\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357210-2-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357208-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28023\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28023\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28023\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28023\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28023\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Luxe&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28023\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/luxe-stride\/\">Luxe<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>128&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 128&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>83&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 83&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28238 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"15\" data-id=\"28238\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357334-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357331-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28238\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/lushat\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28238\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28238\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28238\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28238\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lushat&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28238\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/lushat\/\">Lushat<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>116&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 116&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28058 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable product-type-variable\" data-loop=\"16\" data-id=\"28058\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357531-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357523-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28058\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28058\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28058\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28058\" data-quantity=\"1\" class=\"button product_type_variable add-to-cart-loop\" data-product_id=\"28058\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lunara&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u0642\u0631\u0627\u0621\u0629 \u0627\u0644\u0645\u0632\u064a\u062f<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28058\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/chic-daze\/\">Lunara<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28383 status-publish instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"17\" data-id=\"28383\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357123-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357125-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28383\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28383\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28383\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28383\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28383\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Lumexi&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28383\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/lumexi\/\">Lumexi<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>179&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 179&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>143&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 143&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28415 status-publish instock product_cat-boys product_cat-kids product_cat-shoes-boys has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"18\" data-id=\"28415\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-27%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357450-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357451-1-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28415\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28415\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28415\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28415\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28415\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Kidoo&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28415\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/kidoo\/\">Kidoo<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/\" rel=\"tag\">\u0627\u0644\u0627\u0637\u0641\u0627\u0644<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/\" rel=\"tag\">\u0627\u0644\u0623\u0648\u0644\u0627\u062f<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/kids\/boys\/shoes-boys\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>219&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 219&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>159&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 159&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28375 status-publish last instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"19\" data-id=\"28375\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-20%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357133-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" srcset=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138.png 1024w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-300x300.png 300w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-800x800.png 800w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-150x150.png 150w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-768x768.png 768w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-12x12.png 12w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-430x430.png 430w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-700x700.png 700w, https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357138-500x500.png 500w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28375\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28375\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28375\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28375\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28375\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Kaviro&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28375\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/kaviro\/\">Kaviro<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>187&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 187&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>149&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 149&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"wd-carousel-item\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-product wd-with-labels wd-hover-quick product-grid-item product type-product post-28066 status-publish first instock product_cat-shoes product_cat-women has-post-thumbnail sale shipping-taxable purchasable product-type-variable\" data-loop=\"20\" data-id=\"28066\">\n\t\n\t\n<div class=\"product-wrapper\">\n\t<div class=\"product-element-top wd-quick-shop\">\n\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" class=\"product-image-link\">\n\t\t\t<div class=\"product-labels labels-rounded\"><span class=\"onsale product-label\">-35%<\/span><\/div><img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t<\/a>\n\n\t\t\t\t\t<div class=\"hover-img\">\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" aria-label=\"Product image\">\n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1300\" height=\"1000\" src=\"https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357510-1300x1000.png\" class=\"attachment-1300x1000 size-1300x1000\" alt=\"\" \/>\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t\t<div class=\"wd-buttons wd-pos-r-t\">\n\t\t\t\t\t\t\t\t<div class=\"wd-compare-btn product-compare-button wd-action-btn wd-style-icon wd-compare-icon\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/compare\/\" data-id=\"28066\" rel=\"nofollow\" data-added-text=\"Compare products\">\n\t\t\t\t<span>Compare<\/span>\n\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"quick-view wd-action-btn wd-style-icon wd-quick-view-icon\">\n\t\t\t<a\n\t\t\t\thref=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\"\n\t\t\t\tclass=\"open-quick-view quick-view-button\"\n\t\t\t\trel=\"nofollow\"\n\t\t\t\tdata-id=\"28066\"\n\t\t\t\t>Quick view<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"wd-wishlist-btn wd-action-btn wd-style-icon wd-wishlist-icon\">\n\t\t\t\t<a class=\"\" href=\"https:\/\/savo.ae\/ar\/wishlist\/\" data-key=\"0de3ded08a\" data-product-id=\"28066\" rel=\"nofollow\" data-added-text=\"Browse Wishlist\">\n\t\t\t\t\t<span>Add to wishlist<\/span>\n\t\t\t\t<\/a>\n\t\t\t<\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"wd-add-btn wd-add-btn-replace\">\n\t\t\t\t\n\t\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_28066\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button add-to-cart-loop\" data-product_id=\"28066\" data-product_sku=\"\" aria-label=\"\u062a\u062d\u062f\u064a\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0644\u0640 &quot;Isola&quot;\" rel=\"nofollow\" data-no-translation-aria-label=\"\"><span data-no-translation=\"\" data-trp-gettext=\"\">\u062a\u062d\u062f\u064a\u062f \u0623\u062d\u062f \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a<\/span><\/a>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_28066\" class=\"screen-reader-text\">\n\t\t\u0647\u0646\u0627\u0643 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0634\u0643\u0627\u0644 \u0627\u0644\u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0647\u0630\u0627 \u0627\u0644\u0645\u0646\u062a\u062c. \u064a\u0645\u0643\u0646 \u0627\u062e\u062a\u064a\u0627\u0631 \u0627\u0644\u062e\u064a\u0627\u0631\u0627\u062a \u0639\u0644\u0649 \u0635\u0641\u062d\u0629 \u0627\u0644\u0645\u0646\u062a\u062c\t<\/span>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t<h3 class=\"wd-entities-title\"><a href=\"https:\/\/savo.ae\/ar\/product\/pure-elegance\/\">Isola<\/a><\/h3>\n\t\t\t<div class=\"wd-product-cats\">\n\t\t\t<a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/\" rel=\"tag\">\u0627\u0644\u0645\u0631\u0623\u0629<\/a>, <a href=\"https:\/\/savo.ae\/ar\/product-category\/women\/shoes\/\" rel=\"tag\">\u0627\u0644\u0623\u062d\u0630\u064a\u0629<\/a>\t\t<\/div>\n\t\t\t\t\n\t<span class=\"price\"><del aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>158&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/del> <span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0643\u0627\u0646 \u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u0623\u0635\u0644\u064a: 158&nbsp;AED.<\/span><ins aria-hidden=\"true\"><span class=\"woocommerce-Price-amount amount\"><bdi>103&nbsp;<span class=\"woocommerce-Price-currencySymbol\">AED<\/span><\/bdi><\/span><\/ins><span class=\"screen-reader-text\" data-no-translation=\"\" data-trp-gettext=\"\">\u0627\u0644\u0633\u0639\u0631 \u0627\u0644\u062d\u0627\u0644\u064a \u0647\u0648: 103&nbsp;AED.<\/span><\/span>\n\n\t\n\t\n\t\t<\/div>\n<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"wd-nav-arrows wd-pos-sep wd-hover-1 wd-icon-1\">\n\t\t\t<div class=\"wd-btn-arrow wd-prev wd-disabled\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wd-btn-arrow wd-next\">\n\t\t\t\t<div class=\"wd-arrow-inner\"><\/div>\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t<div class=\"wd-nav-pagin-wrap text-center wd-style-shape wd-hide-md-sm wd-hide-sm\">\n\t\t\t<ul class=\"wd-nav-pagin\"><\/ul>\n\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b794022 e-con-full wd-section-stretch-content e-flex e-con e-parent\" data-id=\"b794022\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;video&quot;,&quot;background_video_link&quot;:&quot;https:\\\/\\\/limegreen-opossum-178043.hostingersite.com\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/1799660_Gift_Wrapping_Gift_Wrap_1920x1080.mp4&quot;,&quot;background_video_start&quot;:0,&quot;background_play_on_mobile&quot;:&quot;yes&quot;}\">\n\t\t<div class=\"elementor-background-video-container\">\n\t\t\t\t\t\t\t<video class=\"elementor-background-video-hosted\" role=\"presentation\" autoplay muted playsinline loop><\/video>\n\t\t\t\t\t<\/div>\t\t<\/div>\n\t\t<div class=\"wd-negative-gap elementor-element elementor-element-c4b2aab wd-section-stretch elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"c4b2aab\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-36286c8 e-con-full e-flex e-con e-child\" data-id=\"36286c8\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6e3e993 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"6e3e993\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\t\u064a\u062f\u0648\u064a\u0627 \u0645\u0639 \u0627\u0644\u0633\u0644\u0627\u0645\u0629\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h3 class=\"woodmart-title-container title wd-fontsize-xxl\">\u0627\u0634\u062a\u0631\u0643 \u0641\u064a \u0642\u0627\u0626\u0645\u062a\u0646\u0627 \u0627\u0644\u0628\u0631\u064a\u062f\u064a\u0629<\/h3> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\t<p>\u0641\u064a \u0628\u064a\u0626\u0629 \u0645\u0647\u0646\u064a\u0629 \u0648\u0643\u062b\u064a\u0631\u0627 \u0645\u0627 \u064a\u062d\u062f\u062b \u0623\u0646 \u0627\u0644\u0642\u0637\u0627\u0639 \u0627\u0644\u062e\u0627\u0635 \u0623\u0648 \u0627\u0644\u0634\u0631\u0643\u0627\u062a.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1767086 e-con-full e-flex e-con e-child\" data-id=\"1767086\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e7537b7 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"e7537b7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-large text-center\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"title-subtitle subtitle-color-default subtitle-style-default wd-fontsize-xs\">\n\t\t\t\t\t\u064a\u062f\u0648\u064a\u0627 \u0645\u0639 \u0627\u0644\u0633\u0644\u0627\u0645\u0629\t\t\t\t<\/div>\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h3 class=\"woodmart-title-container title wd-fontsize-xxl\">\u0647\u0644 \u0644\u062f\u064a\u0643 \u0633\u0624\u0627\u0644 \u061f<\/h3> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<div class=\"title-after_title reset-last-child wd-fontsize-s\">\n\t\t\t\t\t<p>\u0641\u064a \u0628\u064a\u0626\u0629 \u0645\u0647\u0646\u064a\u0629 \u0648\u0643\u062b\u064a\u0631\u0627 \u0645\u0627 \u064a\u062d\u062f\u062b \u0623\u0646 \u0627\u0644\u0642\u0637\u0627\u0639 \u0627\u0644\u062e\u0627\u0635 \u0623\u0648 \u0627\u0644\u0634\u0631\u0643\u0627\u062a.<\/p>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-845536e elementor-widget elementor-widget-wd_popup\" data-id=\"845536e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_popup.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"wd-button-wrapper text-center\" >\n\t\t\t<a class=\"btn btn-style-bordered btn-shape-rectangle btn-size-default wd-open-popup btn-icon-pos-right\"  href=\"#popup-5eec9f61afa34\">\n\t\t\t\t<span class=\"wd-btn-text\" data-elementor-setting-key=\"text\">\n\t\t\t\t\t\u0625\u0631\u0633\u0627\u0644 \u0631\u0633\u0627\u0644\u0629\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t\t<div id=\"popup-5eec9f61afa34\" class=\"wd-popup wd-popup-element wd-entry-content mfp-hide\" style=\"--wd-popup-width:900px;padding:0px;\">\n\t\t\t\t\t\t\t<link rel=\"stylesheet\" id=\"elementor-post-1570-css\" href=\"https:\/\/savo.ae\/wp-content\/uploads\/elementor\/css\/post-1570.css?ver=1778594977\" type=\"text\/css\" media=\"all\">\n\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1570\" class=\"elementor elementor-1570\">\n\t\t\t\t<div class=\"wd-negative-gap elementor-element elementor-element-f25d21b e-flex e-con-boxed e-con e-parent\" data-id=\"f25d21b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4438063 e-con-full e-flex e-con e-child\" data-id=\"4438063\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d71615 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"1d71615\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-default wd-title-style-default wd-title-size-small text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-m\">\u0623\u0631\u0633\u0644 \u0644\u0646\u0627 \u0631\u0633\u0627\u0644\u0629<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cdccc72 elementor-widget elementor-widget-wd_contact_form_7\" data-id=\"cdccc72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_contact_form_7.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1572-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1572\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/ar\/wp-json\/wp\/v2\/pages\/3411#wpcf7-f1572-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\" data-trp-original-action=\"\/ar\/wp-json\/wp\/v2\/pages\/3411#wpcf7-f1572-o1\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1572\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1572-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"row\">\n\t<p class=\"col-md-6\"><label>\u0627\u0633\u0645\u0643<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n\t<p class=\"col-md-6\"><label>\u0627\u0644\u0628\u0631\u064a\u062f \u0627\u0644\u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a \u0627\u0644\u062e\u0627\u0635 \u0628\u0643<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n<\/div>\n<div class=\"row\">\n\t<p class=\"col-md-6\"><label>\u0631\u0642\u0645 \u0627\u0644\u0647\u0627\u062a\u0641<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-767\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-text wpcf7-validates-as-tel\" aria-invalid=\"false\" value=\"\" type=\"tel\" name=\"tel-767\" \/><\/span>\n\t<\/p>\n\t<p class=\"col-md-6\"><label>\u0627\u0644\u0634\u0631\u0643\u0629<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"text-1\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"text-1\" \/><\/span>\n\t<\/p>\n<\/div>\n<p><label>\u0631\u0633\u0627\u0644\u062a\u0643<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner btn-color-black\" type=\"submit\" value=\"\u0627\u0631\u0633\u0627\u0644\" \/>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<input type=\"hidden\" name=\"trp-form-language\" value=\"ar\"\/><\/form>\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-702dc34 color-scheme-light e-con-full e-flex e-con e-child\" data-id=\"702dc34\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8346027 wd-width-100 elementor-widget elementor-widget-wd_title\" data-id=\"8346027\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"title-wrapper wd-set-mb reset-last-child wd-title-color-white wd-title-style-default wd-title-size-small text-left\">\n\n\t\t\t\n\t\t\t<div class=\"liner-continer\">\n\t\t\t\t<h4 class=\"woodmart-title-container title wd-fontsize-m\">\u0645\u0639\u0644\u0648\u0645\u0627\u062a \u0627\u0644\u0627\u062a\u0635\u0627\u0644<\/h4> \n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-794b471 elementor-widget elementor-widget-wd_infobox\" data-id=\"794b471\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme- wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width:30px; height:30px;\"><img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/savo.ae\/wp-content\/uploads\/2021\/09\/wd-pointer.svg\" title=\"wd-\u0627\u0644\u0645\u0624\u0634\u0631\" width=\"30\" height=\"30\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p>50 East 52nd Street<br \/>\u0628\u0631\u0648\u0643\u0644\u064a\u0646, NY 10022<br \/>\u0627\u0644\u0648\u0644\u0627\u064a\u0627\u062a \u0627\u0644\u0645\u062a\u062d\u062f\u0629<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-info-box-link wd-fill\" aria-label=\"Infobox link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29edaba elementor-widget elementor-widget-wd_infobox\" data-id=\"29edaba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme- wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width:30px; height:30px;\"><img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/savo.ae\/wp-content\/uploads\/2021\/09\/wd-mobile.svg\" title=\"wd-mobile\" width=\"30\" height=\"30\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p>+1322224332<br \/>+4643758533<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-info-box-link wd-fill\" aria-label=\"Infobox link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f93fe75 elementor-widget elementor-widget-wd_infobox\" data-id=\"f93fe75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_infobox.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"info-box-wrapper\">\n\t\t\t<div class=\"wd-info-box text-left box-icon-align-left box-style-base color-scheme- wd-items-top\">\n\t\t\t\t\t\t\t\t\t<div class=\"box-icon-wrapper  box-with-icon box-icon-simple\">\n\t\t\t\t\t\t<div class=\"info-box-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"info-svg-wrapper\" style=\"width:30px; height:30px;\"><img loading=\"lazy\" decoding=\"async\"  src=\"https:\/\/savo.ae\/wp-content\/uploads\/2021\/09\/wd-paper-plane.svg\" title=\"wd-\u0627\u0644\u0648\u0631\u0642-\u0627\u0644\u0637\u0627\u0626\u0631\u0629\" width=\"30\" height=\"30\"><\/div>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\n\t\t\t\t<div class=\"info-box-content\">\n\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t\t<div class=\"info-box-inner reset-last-child\"data-elementor-setting-key=\"content\"><p>info@google.com<br \/>support@google.com<\/p>\n<\/div>\n\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t\t<a href=\"#\" class=\"wd-info-box-link wd-fill\" aria-label=\"Infobox link\"><\/a>\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b63ac0c color-scheme-light text-left elementor-widget elementor-widget-text-editor\" data-id=\"b63ac0c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p>\u0647\u0644 \u0644\u062f\u064a\u0643 \u0623\u0633\u0626\u0644\u0629 \u062d\u0648\u0644 \u0643\u064a\u0641 \u064a\u0645\u0643\u0646\u0646\u0627 \u0645\u0633\u0627\u0639\u062f\u0629 \u0634\u0631\u0643\u062a\u0643 \u061f \u0625\u0631\u0633\u0627\u0644 \u0628\u0631\u064a\u062f \u0625\u0644\u0643\u062a\u0631\u0648\u0646\u064a \u0625\u0644\u064a\u0646\u0627 \u0648\u0646\u062d\u0646 \u0633\u0648\u0641 \u062a\u062d\u0635\u0644 \u0639\u0644\u0649 \u0627\u062a\u0635\u0627\u0644 \u0642\u0631\u064a\u0628\u0627.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8d60138 elementor-widget elementor-widget-wd_social_buttons\" data-id=\"8d60138\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wd_social_buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<div id=\"\" class=\"wd-social-icons wd-style-colored wd-size-small social-share wd-shape-circle color-scheme-dark text-left\">\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.facebook.com\/sharer\/sharer.php?u=https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" target=\"_blank\" class=\"wd-social-icon social-facebook\" aria-label=\"Facebook social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/x.com\/share?url=https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" target=\"_blank\" class=\"wd-social-icon social-twitter\" aria-label=\"X social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/pinterest.com\/pin\/create\/button\/?url=https:\/\/savo.ae\/ar\/product\/pure-elegance\/&media=https:\/\/savo.ae\/wp-content\/uploads\/2026\/02\/1000357515.png&description=Isola\" target=\"_blank\" class=\"wd-social-icon social-pinterest\" aria-label=\"Pinterest social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" target=\"_blank\" class=\"wd-social-icon social-linkedin\" aria-label=\"Linkedin social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<a rel=\"noopener noreferrer nofollow\" href=\"https:\/\/telegram.me\/share\/url?url=https:\/\/savo.ae\/ar\/product\/pure-elegance\/\" target=\"_blank\" class=\"wd-social-icon social-tg\" aria-label=\"Telegram social link\">\n\t\t\t\t\t\t<span class=\"wd-icon\"><\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Shop Now Savo \u2013\u00a0Your Style, Your Statement Shop Now Shop Now Step Into Style\u00a0 with Savo Shop Now Shop Now<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3411","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/savo.ae\/ar\/wp-json\/wp\/v2\/pages\/3411","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/savo.ae\/ar\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/savo.ae\/ar\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/savo.ae\/ar\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/savo.ae\/ar\/wp-json\/wp\/v2\/comments?post=3411"}],"version-history":[{"count":66,"href":"https:\/\/savo.ae\/ar\/wp-json\/wp\/v2\/pages\/3411\/revisions"}],"predecessor-version":[{"id":28201,"href":"https:\/\/savo.ae\/ar\/wp-json\/wp\/v2\/pages\/3411\/revisions\/28201"}],"wp:attachment":[{"href":"https:\/\/savo.ae\/ar\/wp-json\/wp\/v2\/media?parent=3411"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}